{"id":122,"date":"2018-01-19T15:32:59","date_gmt":"2018-01-19T14:32:59","guid":{"rendered":"https:\/\/www.thevinyl.se\/?page_id=122"},"modified":"2024-07-04T15:14:36","modified_gmt":"2024-07-04T13:14:36","slug":"yhteystiedot","status":"publish","type":"page","link":"https:\/\/www.thevinyl.se\/fi\/yhteystiedot\/","title":{"rendered":"Yhteystiedot"},"content":{"rendered":"\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f143-o1\" lang=\"sv-SE\" dir=\"ltr\" data-wpcf7-id=\"143\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fi\/wp-json\/wp\/v2\/pages\/122#wpcf7-f143-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformul\u00e4r\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"143\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"sv_SE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f143-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p class=\"form-col\"><label for=\"your-name\">Nimi: *<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"your-name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p class=\"form-col\"><label for=\"your-email\">S\u00e4hk\u00f6postiosoite: *<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"your-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><label for=\"for-whom\">Mihin osastoon haluat ottaa yhteytt\u00e4?<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"for-whom\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" id=\"for-whom\" aria-required=\"true\" aria-invalid=\"false\" name=\"for-whom\"><option value=\"Toimisto\">Toimisto<\/option><option value=\"TJ\">TJ<\/option><option value=\"Logistiikka ja taloushallinto\">Logistiikka ja taloushallinto<\/option><option value=\"Tuotannonsuunnittelu\">Tuotannonsuunnittelu<\/option><option value=\"Tuotanto ja kunnossapito\">Tuotanto ja kunnossapito<\/option><option value=\"Kehity ja ymp\u00e4rist\u00f6\">Kehity ja ymp\u00e4rist\u00f6<\/option><\/select><\/span>\n<\/p>\n<p><label for=\"your-message\">Viesti: *<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" id=\"your-message\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span><span id=\"wpcf7-6a56d807691df-wrapper\" class=\"wpcf7-form-control-wrap email-here-wrap\" data-cf7apps-honeypot=\"email-here\" style=\"display: block;\n\t\t    width: 0px;\n\t\t    height: 0px;\n\t\t    padding: 0px;\n\t\t    border: 1px solid transparent;\n\t\t    display: block;\n\t\t    overflow: hidden;\n\t\t    \"><input type=\"hidden\" name=\"email-here-random-hash\" value=\"86118642\"><label\n\t\t    for=\"email-here\"\n\t\t    class=\"hp-message\"\n        >L\u00e4mna detta f\u00e4lt tomt.<\/label><input\n\t    id=\"email-here\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"v6jbhicoafny\"\n\t    value=\"\"\n\t    size=\"40\"\n\t    autocomplete=\"new-password\"\n\t    tabindex=\"1000\"\n    \/><\/span>\n<\/p>\n<p id=\"acceptance\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-consent\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"your-consent\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Olen lukenut <a href=\"https:\/\/www.thevinyl.se\/fi\/gdpr-tietosuojaseloste\/\" target=\"_blank\">tietosuojaselosteen<\/a> ja hyv\u00e4ksyn ehdot.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p id=\"submit\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"L\u00e4het\u00e4\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":50,"comment_status":"closed","ping_status":"closed","template":"kontakt.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-122","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.thevinyl.se\/fi\/wp-json\/wp\/v2\/pages\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thevinyl.se\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.thevinyl.se\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.thevinyl.se\/fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thevinyl.se\/fi\/wp-json\/wp\/v2\/comments?post=122"}],"version-history":[{"count":14,"href":"https:\/\/www.thevinyl.se\/fi\/wp-json\/wp\/v2\/pages\/122\/revisions"}],"predecessor-version":[{"id":405,"href":"https:\/\/www.thevinyl.se\/fi\/wp-json\/wp\/v2\/pages\/122\/revisions\/405"}],"wp:attachment":[{"href":"https:\/\/www.thevinyl.se\/fi\/wp-json\/wp\/v2\/media?parent=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}